{"id":342,"date":"2020-06-21T16:56:25","date_gmt":"2020-06-21T14:56:25","guid":{"rendered":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/?p=342"},"modified":"2020-06-21T17:02:04","modified_gmt":"2020-06-21T15:02:04","slug":"plus-que-quelques-heures","status":"publish","type":"post","link":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/plus-que-quelques-heures\/","title":{"rendered":"Plus que quelques heures&#8230;"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"342\" class=\"elementor elementor-342\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f0b36d2 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5f0b36d2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5ee4f5ee\" data-id=\"5ee4f5ee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26cfabe2 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"26cfabe2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Plus que quelques heures&#8230;<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-402939b8 elementor-widget elementor-widget-gallery\" data-id=\"402939b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;gallery_layout&quot;:&quot;justified&quot;,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;lazyload&quot;:&quot;yes&quot;,&quot;ideal_row_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:200,&quot;sizes&quot;:[]},&quot;ideal_row_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:150,&quot;sizes&quot;:[]},&quot;ideal_row_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:150,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/WhatsApp-Image-2020-06-20-at-10.30.14.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"402939b8\" data-elementor-lightbox-title=\"WhatsApp Image 2020-06-20 at 10.30.14\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzQzLCJ1cmwiOiJodHRwczpcL1wvdHJvcGlxdWVzLWF0cml1bS5mclwvZmV0ZS1kZS1sYS1tdXNpcXVlXC93cC1jb250ZW50XC91cGxvYWRzXC9zaXRlc1wvNlwvMjAyMFwvMDZcL1doYXRzQXBwLUltYWdlLTIwMjAtMDYtMjAtYXQtMTAuMzAuMTQuanBlZyIsInNsaWRlc2hvdyI6IjQwMjkzOWI4In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/WhatsApp-Image-2020-06-20-at-10.30.14.jpeg\" data-width=\"1280\" data-height=\"720\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/WhatsApp-Image-2020-06-20-at-14.27.42.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"402939b8\" data-elementor-lightbox-title=\"WhatsApp Image 2020-06-20 at 14.27.42\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzQ0LCJ1cmwiOiJodHRwczpcL1wvdHJvcGlxdWVzLWF0cml1bS5mclwvZmV0ZS1kZS1sYS1tdXNpcXVlXC93cC1jb250ZW50XC91cGxvYWRzXC9zaXRlc1wvNlwvMjAyMFwvMDZcL1doYXRzQXBwLUltYWdlLTIwMjAtMDYtMjAtYXQtMTQuMjcuNDIuanBlZyIsInNsaWRlc2hvdyI6IjQwMjkzOWI4In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/WhatsApp-Image-2020-06-20-at-14.27.42.jpeg\" data-width=\"1280\" data-height=\"720\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/WhatsApp-Image-2020-06-20-at-16.54.02-1.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"402939b8\" data-elementor-lightbox-title=\"WhatsApp Image 2020-06-20 at 16.54.02 (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzQ1LCJ1cmwiOiJodHRwczpcL1wvdHJvcGlxdWVzLWF0cml1bS5mclwvZmV0ZS1kZS1sYS1tdXNpcXVlXC93cC1jb250ZW50XC91cGxvYWRzXC9zaXRlc1wvNlwvMjAyMFwvMDZcL1doYXRzQXBwLUltYWdlLTIwMjAtMDYtMjAtYXQtMTYuNTQuMDItMS5qcGVnIiwic2xpZGVzaG93IjoiNDAyOTM5YjgifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/WhatsApp-Image-2020-06-20-at-16.54.02-1.jpeg\" data-width=\"1032\" data-height=\"774\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/WhatsApp-Image-2020-06-20-at-17.18.27.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"402939b8\" data-elementor-lightbox-title=\"WhatsApp Image 2020-06-20 at 17.18.27\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzQ3LCJ1cmwiOiJodHRwczpcL1wvdHJvcGlxdWVzLWF0cml1bS5mclwvZmV0ZS1kZS1sYS1tdXNpcXVlXC93cC1jb250ZW50XC91cGxvYWRzXC9zaXRlc1wvNlwvMjAyMFwvMDZcL1doYXRzQXBwLUltYWdlLTIwMjAtMDYtMjAtYXQtMTcuMTguMjcuanBlZyIsInNsaWRlc2hvdyI6IjQwMjkzOWI4In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/WhatsApp-Image-2020-06-20-at-17.18.27.jpeg\" data-width=\"1032\" data-height=\"774\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/WhatsApp-Image-2020-06-20-at-16.54.02.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"402939b8\" data-elementor-lightbox-title=\"WhatsApp Image 2020-06-20 at 16.54.02\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzQ2LCJ1cmwiOiJodHRwczpcL1wvdHJvcGlxdWVzLWF0cml1bS5mclwvZmV0ZS1kZS1sYS1tdXNpcXVlXC93cC1jb250ZW50XC91cGxvYWRzXC9zaXRlc1wvNlwvMjAyMFwvMDZcL1doYXRzQXBwLUltYWdlLTIwMjAtMDYtMjAtYXQtMTYuNTQuMDIuanBlZyIsInNsaWRlc2hvdyI6IjQwMjkzOWI4In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/WhatsApp-Image-2020-06-20-at-16.54.02.jpeg\" data-width=\"1032\" data-height=\"774\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/WhatsApp-Image-2020-06-20-at-18.58.18.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"402939b8\" data-elementor-lightbox-title=\"WhatsApp Image 2020-06-20 at 18.58.18\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzQ4LCJ1cmwiOiJodHRwczpcL1wvdHJvcGlxdWVzLWF0cml1bS5mclwvZmV0ZS1kZS1sYS1tdXNpcXVlXC93cC1jb250ZW50XC91cGxvYWRzXC9zaXRlc1wvNlwvMjAyMFwvMDZcL1doYXRzQXBwLUltYWdlLTIwMjAtMDYtMjAtYXQtMTguNTguMTguanBlZyIsInNsaWRlc2hvdyI6IjQwMjkzOWI4In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/WhatsApp-Image-2020-06-20-at-18.58.18.jpeg\" data-width=\"1280\" data-height=\"768\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/WhatsApp-Image-2020-06-20-at-19.12.18.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"402939b8\" data-elementor-lightbox-title=\"WhatsApp Image 2020-06-20 at 19.12.18\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzQ5LCJ1cmwiOiJodHRwczpcL1wvdHJvcGlxdWVzLWF0cml1bS5mclwvZmV0ZS1kZS1sYS1tdXNpcXVlXC93cC1jb250ZW50XC91cGxvYWRzXC9zaXRlc1wvNlwvMjAyMFwvMDZcL1doYXRzQXBwLUltYWdlLTIwMjAtMDYtMjAtYXQtMTkuMTIuMTguanBlZyIsInNsaWRlc2hvdyI6IjQwMjkzOWI4In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/WhatsApp-Image-2020-06-20-at-19.12.18.jpeg\" data-width=\"1280\" data-height=\"720\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da9ed2d elementor-widget elementor-widget-heading\" data-id=\"da9ed2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Montage et balances depuis hier ! La sc\u00e8ne est pr\u00eate et n'attend plus que vous pour cette f\u00eate de la musique 2020 !<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e75e9af elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e75e9af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74522b47 elementor-widget elementor-widget-text-editor\" data-id=\"74522b47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lire aussi<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73543e79 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"73543e79\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;pagination_type&quot;:&quot;numbers&quot;,&quot;classic_columns&quot;:&quot;3&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-332 post type-post status-publish format-standard has-post-thumbnail hentry category-news\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/interview-de-dore-sowlo\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/Dore\u0301-itw-1024x576.jpg\" class=\"attachment-large size-large wp-image-328\" alt=\"\" srcset=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/Dore\u0301-itw-1024x576.jpg 1024w, https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/Dore\u0301-itw-300x169.jpg 300w, https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/Dore\u0301-itw-768x432.jpg 768w, https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/Dore\u0301-itw-1536x864.jpg 1536w, https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/Dore\u0301-itw.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/interview-de-dore-sowlo\/\" >\n\t\t\t\tInterview de Dor\u00e9 Sowlo\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1 post type-post status-publish format-standard has-post-thumbnail hentry category-news\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/filage-jann\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1024\" height=\"754\" src=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/jann-1024x754.jpg\" class=\"attachment-large size-large wp-image-153\" alt=\"\" srcset=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/jann-1024x754.jpg 1024w, https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/jann-300x221.jpg 300w, https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/jann-768x565.jpg 768w, https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/jann.jpg 1064w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/filage-jann\/\" >\n\t\t\t\tSortie de filage pour Jann !\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-318 post type-post status-publish format-standard has-post-thumbnail hentry category-news\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/les-gestes-barrieres\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"694\" height=\"1024\" src=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/AFFICHE-COVID-copie-694x1024.jpg\" class=\"attachment-large size-large wp-image-317\" alt=\"\" srcset=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/AFFICHE-COVID-copie-694x1024.jpg 694w, https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/AFFICHE-COVID-copie-203x300.jpg 203w, https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/AFFICHE-COVID-copie-768x1133.jpg 768w, https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/AFFICHE-COVID-copie-1041x1536.jpg 1041w, https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/AFFICHE-COVID-copie-1388x2048.jpg 1388w, https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/AFFICHE-COVID-copie-scaled.jpg 1735w\" sizes=\"(max-width: 694px) 100vw, 694px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/les-gestes-barrieres\/\" >\n\t\t\t\tLes gestes barri\u00e8res\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"e-load-more-anchor\" data-page=\"1\" data-max-page=\"3\" data-next-page=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-json\/wp\/v2\/posts\/342\/page\/2\/\"><\/div>\n\t\t\t\t<nav class=\"elementor-pagination\" aria-label=\"Pagination\">\n\t\t\t<span aria-current=\"page\" class=\"page-numbers current\"><span class=\"elementor-screen-only\">Page<\/span>1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-json\/wp\/v2\/posts\/342\/page\/2\/\"><span class=\"elementor-screen-only\">Page<\/span>2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-json\/wp\/v2\/posts\/342\/page\/3\/\"><span class=\"elementor-screen-only\">Page<\/span>3<\/a>\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-770b44f7 elementor-share-buttons--skin-minimal elementor-share-buttons--color-custom elementor-share-buttons--view-icon-text elementor-share-buttons--shape-square elementor-grid-0 elementor-widget elementor-widget-share-buttons\" data-id=\"770b44f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-facebook\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_twitter\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur twitter\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-twitter\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_whatsapp\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur whatsapp\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-whatsapp\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Montage et balances depuis hier ! La sc\u00e8ne est pr\u00eate et n&#8217;attend plus que vous pour cette f\u00eate de la musique 2020 ! Lire aussi<\/p>\n","protected":false},"author":2,"featured_media":345,"comment_status":"open","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-342","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plus que quelques heures... - La F\u00eate de la Musique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/plus-que-quelques-heures\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plus que quelques heures... - La F\u00eate de la Musique\" \/>\n<meta property=\"og:description\" content=\"Montage et balances depuis hier ! La sc\u00e8ne est pr\u00eate et n&#8217;attend plus que vous pour cette f\u00eate de la musique 2020 ! Lire aussi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/plus-que-quelques-heures\/\" \/>\n<meta property=\"og:site_name\" content=\"La F\u00eate de la Musique\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-21T14:56:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-21T15:02:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/WhatsApp-Image-2020-06-20-at-16.54.02-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1032\" \/>\n\t<meta property=\"og:image:height\" content=\"774\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"keith\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"keith\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plus que quelques heures... - La F\u00eate de la Musique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/plus-que-quelques-heures\/","og_locale":"fr_FR","og_type":"article","og_title":"Plus que quelques heures... - La F\u00eate de la Musique","og_description":"Montage et balances depuis hier ! La sc\u00e8ne est pr\u00eate et n&#8217;attend plus que vous pour cette f\u00eate de la musique 2020 ! Lire aussi","og_url":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/plus-que-quelques-heures\/","og_site_name":"La F\u00eate de la Musique","article_published_time":"2020-06-21T14:56:25+00:00","article_modified_time":"2020-06-21T15:02:04+00:00","og_image":[{"width":1032,"height":774,"url":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/WhatsApp-Image-2020-06-20-at-16.54.02-1.jpeg","type":"image\/jpeg"}],"author":"keith","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"keith"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/plus-que-quelques-heures\/#article","isPartOf":{"@id":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/plus-que-quelques-heures\/"},"author":{"name":"keith","@id":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/#\/schema\/person\/139f7f207568015da565e4614aeca7db"},"headline":"Plus que quelques heures&#8230;","datePublished":"2020-06-21T14:56:25+00:00","dateModified":"2020-06-21T15:02:04+00:00","mainEntityOfPage":{"@id":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/plus-que-quelques-heures\/"},"wordCount":42,"commentCount":0,"publisher":{"@id":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/#organization"},"image":{"@id":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/plus-que-quelques-heures\/#primaryimage"},"thumbnailUrl":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/WhatsApp-Image-2020-06-20-at-16.54.02-1.jpeg","articleSection":["news"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/plus-que-quelques-heures\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/plus-que-quelques-heures\/","url":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/plus-que-quelques-heures\/","name":"Plus que quelques heures... - La F\u00eate de la Musique","isPartOf":{"@id":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/plus-que-quelques-heures\/#primaryimage"},"image":{"@id":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/plus-que-quelques-heures\/#primaryimage"},"thumbnailUrl":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/WhatsApp-Image-2020-06-20-at-16.54.02-1.jpeg","datePublished":"2020-06-21T14:56:25+00:00","dateModified":"2020-06-21T15:02:04+00:00","breadcrumb":{"@id":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/plus-que-quelques-heures\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/plus-que-quelques-heures\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/plus-que-quelques-heures\/#primaryimage","url":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/WhatsApp-Image-2020-06-20-at-16.54.02-1.jpeg","contentUrl":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/WhatsApp-Image-2020-06-20-at-16.54.02-1.jpeg","width":1032,"height":774},{"@type":"BreadcrumbList","@id":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/plus-que-quelques-heures\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/"},{"@type":"ListItem","position":2,"name":"Plus que quelques heures&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/#website","url":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/","name":"La F\u00eate de la Musique","description":"","publisher":{"@id":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/#organization","name":"La F\u00eate de la Musique","url":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/#\/schema\/logo\/image\/","url":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/logo_tropiques_atrium_400px.png","contentUrl":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/logo_tropiques_atrium_400px.png","width":300,"height":150,"caption":"La F\u00eate de la Musique"},"image":{"@id":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/#\/schema\/person\/139f7f207568015da565e4614aeca7db","name":"keith","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/1072737de7c1116566cea75d095b0cd6eb169ee0a6e81d467cad292c2ae56286?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1072737de7c1116566cea75d095b0cd6eb169ee0a6e81d467cad292c2ae56286?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1072737de7c1116566cea75d095b0cd6eb169ee0a6e81d467cad292c2ae56286?s=96&d=mm&r=g","caption":"keith"},"url":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/author\/keith\/"}]}},"jetpack_featured_media_url":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-content\/uploads\/sites\/6\/2020\/06\/WhatsApp-Image-2020-06-20-at-16.54.02-1.jpeg","jetpack_sharing_enabled":true,"amp_enabled":false,"_links":{"self":[{"href":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-json\/wp\/v2\/posts\/342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-json\/wp\/v2\/comments?post=342"}],"version-history":[{"count":6,"href":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-json\/wp\/v2\/posts\/342\/revisions"}],"predecessor-version":[{"id":355,"href":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-json\/wp\/v2\/posts\/342\/revisions\/355"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-json\/wp\/v2\/media\/345"}],"wp:attachment":[{"href":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-json\/wp\/v2\/media?parent=342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-json\/wp\/v2\/categories?post=342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tropiques-atrium.fr\/fete-de-la-musique\/wp-json\/wp\/v2\/tags?post=342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}