{"id":12051,"date":"2022-10-12T03:12:09","date_gmt":"2022-10-12T01:12:09","guid":{"rendered":"https:\/\/tropiques-atrium.fr\/cinemartinique\/?page_id=12051"},"modified":"2024-10-04T23:14:21","modified_gmt":"2024-10-04T21:14:21","slug":"prix-du-jury-court-metrage","status":"publish","type":"page","link":"https:\/\/tropiques-atrium.fr\/cinemartinique\/les-films-en-competition\/prix-du-jury-court-metrage\/","title":{"rendered":"Prix du jury Court-m\u00e9trage"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"12051\" class=\"elementor elementor-12051\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-74efd6c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74efd6c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0b5bb39\" data-id=\"0b5bb39\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7035bb elementor-align-left elementor-widget elementor-widget-breadcrumbs\" data-id=\"e7035bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/tropiques-atrium.fr\/cinemartinique\/\">Accueil<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f3d954 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3f3d954\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1cb8d05 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1cb8d05\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4e79620\" data-id=\"4e79620\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f544ee elementor-widget elementor-widget-text-editor\" data-id=\"4f544ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Prix du jury Court-m\u00e9trage.<br \/>LES COURT-METRAGES EN COMP\u00c9TITION<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cd658ef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cd658ef\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-87f66fc\" data-id=\"87f66fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15ad361 elementor-widget elementor-widget-text-editor\" data-id=\"15ad361\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le jury<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2fecd0b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2fecd0b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-19e3ed5\" data-id=\"19e3ed5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88adb0a elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"88adb0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1600\" height=\"2000\" src=\"https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet.jpg\" class=\"attachment-full size-full wp-image-15016\" alt=\"\" srcset=\"https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet.jpg 1600w, https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet-240x300.jpg 240w, https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet-819x1024.jpg 819w, https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet-768x960.jpg 768w, https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet-1229x1536.jpg 1229w, https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet-585x731.jpg 585w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">[A venir]<\/h3><p class=\"elementor-image-box-description\">Le jury sera d\u00e9voil\u00e9 bient\u00f4t !<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-fa570e2\" data-id=\"fa570e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1093c5c elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"1093c5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1600\" height=\"2000\" src=\"https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet.jpg\" class=\"attachment-full size-full wp-image-15016\" alt=\"\" srcset=\"https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet.jpg 1600w, https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet-240x300.jpg 240w, https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet-819x1024.jpg 819w, https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet-768x960.jpg 768w, https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet-1229x1536.jpg 1229w, https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet-585x731.jpg 585w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">[A venir]<\/h3><p class=\"elementor-image-box-description\">Le jury sera d\u00e9voil\u00e9 bient\u00f4t !<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4f03663\" data-id=\"4f03663\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eee9470 elementor-position-left elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"eee9470\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1600\" height=\"2000\" src=\"https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet.jpg\" class=\"attachment-full size-full wp-image-15016\" alt=\"\" srcset=\"https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet.jpg 1600w, https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet-240x300.jpg 240w, https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet-819x1024.jpg 819w, https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet-768x960.jpg 768w, https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet-1229x1536.jpg 1229w, https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet-585x731.jpg 585w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">[A venir]<\/h3><p class=\"elementor-image-box-description\">Le jury sera d\u00e9voil\u00e9 bient\u00f4t !<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-b0089a4\" data-id=\"b0089a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d99ddb8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d99ddb8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6968c2d\" data-id=\"6968c2d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f0c3dc elementor-widget elementor-widget-text-editor\" data-id=\"3f0c3dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p id=\"evo_set_shortcodes\"><!-- EventON Calendar --><div id='evcal_calendar_874' class='ajde_evcal_calendar sev clean esty_4 etttc_custom ajax_loading_cal' data-cal=''><div id='evcal_head' class='calendar_header evcal_nosort' ><div class='evo_cal_above evodfx evofx_dr_r marb5 evofx_ww'><button class='cal_head_btn evo-gototoday-btn' style='' data-mo='9' data-yr='2026' data-dy='' aria-label='Go to today'>Ce mois-ci<\/button><\/div><div class='evo_cal_above_content'><\/div><div class='evo_header_title '><div class='evo_header_mo evodfx evofx_ai_c'><div class='evo_loading_bar_holder h100 noMinH swipe' style=''><div class='evo_loading_bar wid_80% hi_40px' style='width:80%; height:40px; '><\/div><\/div><\/div><\/div><\/div><div class='evo_filter_bar evo_main_filter_bar eventon_sorting_section '><div class='evo_filter_container evodfx evo_fx_ai_c'><div class='evo_filter_container_in'><div class='eventon_filter_line' ><div class='evo_loading_bar_holder h100 loading_filters swipe' style='min-height:30px;'><div class='nesthold r g10'><div class='evo_loading_bar wid_100% hi_30px' style='width:100%; height:30px; margin-bottom:1px;'><\/div><div class='evo_loading_bar wid_100% hi_30px' style='width:100%; height:30px; margin-bottom:1px;'><\/div><div class='evo_loading_bar wid_100% hi_30px' style='width:100%; height:30px; margin-bottom:1px;'><\/div><div class='evo_loading_bar wid_100% hi_30px' style='width:100%; height:30px; margin-bottom:1px;'><\/div><div class='evo_loading_bar wid_100% hi_30px' style='width:100%; height:30px; margin-bottom:1px;'><\/div><\/div><\/div><\/div><\/div><div class='evo_filter_nav evo_filter_l'><i class='fa fa-chevron-left'><\/i><\/div><div class='evo_filter_nav evo_filter_r'><i class='fa fa-chevron-right'><\/i><\/div><\/div><div class='evo_filter_aply_btns'><\/div><div class='evo_filter_menu'><\/div><\/div><div id='eventon_loadbar_section'><div id='eventon_loadbar'><\/div><\/div><!-- Events List --><div class='evo_events_list_box'><div id='evcal_list' class='eventon_events_list '><div class='evo_loading_bar_holder h100 loading_e swipe' style=''><div class='nest nest1 e'><div class='nesthold r g10'><div class='nest nest2 e1'><div class='evo_loading_bar wid_100px hi_95px' style='width:100px; height:95px; '><\/div><\/div><div class='nest nest2 e2'><div class='evo_loading_bar wid_50% hi_55px' style='width:50%; height:55px; '><\/div><div class='evo_loading_bar wid_90% hi_30px' style='width:90%; height:30px; '><\/div><\/div><\/div><\/div><div class='nest nest1 e'><div class='nesthold r g10'><div class='nest nest2 e1'><div class='evo_loading_bar wid_100px hi_95px' style='width:100px; height:95px; '><\/div><\/div><div class='nest nest2 e2'><div class='evo_loading_bar wid_50% hi_55px' style='width:50%; height:55px; '><\/div><div class='evo_loading_bar wid_90% hi_30px' style='width:90%; height:30px; '><\/div><\/div><\/div><\/div><div class='nest nest1 e'><div class='nesthold r g10'><div class='nest nest2 e1'><div class='evo_loading_bar wid_100px hi_95px' style='width:100px; height:95px; '><\/div><\/div><div class='nest nest2 e2'><div class='evo_loading_bar wid_50% hi_55px' style='width:50%; height:55px; '><\/div><div class='evo_loading_bar wid_90% hi_30px' style='width:90%; height:30px; '><\/div><\/div><\/div><\/div><\/div>\t\t\t<\/div>\r\n\t\t\t<\/div><!-- evo_events_list_box -->\t\r\n\t\t\t<div class='clear'><\/div>\r\n\t\t\t\t\t \t<div id='evcal_footer' class='evo_bottom' style='display:none'>\r\n\t\t \t\t<div class='evo_cal_data' data-sc=\"{&quot;accord&quot;:&quot;no&quot;,&quot;bottom_nav&quot;:&quot;no&quot;,&quot;cal_id&quot;:&quot;&quot;,&quot;cal_init_nonajax&quot;:&quot;no&quot;,&quot;calendar_type&quot;:&quot;default&quot;,&quot;day_incre&quot;:0,&quot;ehover&quot;:&quot;def&quot;,&quot;ep_fields&quot;:&quot;&quot;,&quot;etc_override&quot;:&quot;yes&quot;,&quot;evc_open&quot;:&quot;no&quot;,&quot;event_count&quot;:0,&quot;event_location&quot;:&quot;all&quot;,&quot;event_order&quot;:&quot;ASC&quot;,&quot;event_organizer&quot;:&quot;all&quot;,&quot;event_parts&quot;:&quot;no&quot;,&quot;event_past_future&quot;:&quot;all&quot;,&quot;event_status&quot;:&quot;all&quot;,&quot;event_tag&quot;:&quot;all&quot;,&quot;event_type&quot;:&quot;11,6,&quot;,&quot;event_type_2&quot;:&quot;all&quot;,&quot;event_virtual&quot;:&quot;all&quot;,&quot;eventtop_date_style&quot;:0,&quot;eventtop_style&quot;:&quot;4&quot;,&quot;exp_jumper&quot;:&quot;no&quot;,&quot;exp_so&quot;:&quot;no&quot;,&quot;filter_relationship&quot;:&quot;AND&quot;,&quot;filter_show_set_only&quot;:&quot;no&quot;,&quot;filter_style&quot;:&quot;default&quot;,&quot;filter_type&quot;:&quot;default&quot;,&quot;filters&quot;:&quot;yes&quot;,&quot;fixed_day&quot;:&quot;2&quot;,&quot;fixed_month&quot;:&quot;9&quot;,&quot;fixed_year&quot;:&quot;2026&quot;,&quot;focus_end_date_range&quot;:&quot;1790827199&quot;,&quot;focus_start_date_range&quot;:&quot;1788235200&quot;,&quot;ft_event_priority&quot;:&quot;no&quot;,&quot;grid_ux&quot;:0,&quot;heat&quot;:&quot;no&quot;,&quot;hide_arrows&quot;:&quot;no&quot;,&quot;hide_cancels&quot;:&quot;no&quot;,&quot;hide_empty_months&quot;:&quot;no&quot;,&quot;hide_end_time&quot;:&quot;no&quot;,&quot;hide_et_dn&quot;:&quot;no&quot;,&quot;hide_et_extra&quot;:&quot;no&quot;,&quot;hide_et_tags&quot;:&quot;no&quot;,&quot;hide_et_tl&quot;:&quot;no&quot;,&quot;hide_ft&quot;:&quot;no&quot;,&quot;hide_ft_img&quot;:&quot;no&quot;,&quot;hide_month_headers&quot;:&quot;no&quot;,&quot;hide_mult_occur&quot;:&quot;no&quot;,&quot;hide_past&quot;:&quot;no&quot;,&quot;hide_past_by&quot;:&quot;ee&quot;,&quot;hide_so&quot;:&quot;yes&quot;,&quot;hide_sort_options&quot;:&quot;no&quot;,&quot;hover&quot;:&quot;number&quot;,&quot;ics&quot;:&quot;no&quot;,&quot;jumper&quot;:&quot;no&quot;,&quot;jumper_count&quot;:5,&quot;jumper_offset&quot;:&quot;0&quot;,&quot;lang&quot;:&quot;L1&quot;,&quot;layout_changer&quot;:&quot;no&quot;,&quot;livenow_bar&quot;:&quot;yes&quot;,&quot;load_fullmonth&quot;:&quot;no&quot;,&quot;mapformat&quot;:&quot;roadmap&quot;,&quot;mapiconurl&quot;:&quot;&quot;,&quot;maps_load&quot;:&quot;yes&quot;,&quot;mapscroll&quot;:&quot;true&quot;,&quot;mapzoom&quot;:&quot;18&quot;,&quot;members_only&quot;:&quot;no&quot;,&quot;ml_priority&quot;:&quot;no&quot;,&quot;ml_toend&quot;:&quot;no&quot;,&quot;mo1st&quot;:&quot;&quot;,&quot;month_incre&quot;:0,&quot;nexttogrid&quot;:&quot;no&quot;,&quot;number_of_months&quot;:&quot;1&quot;,&quot;only_ft&quot;:&quot;no&quot;,&quot;pec&quot;:&quot;&quot;,&quot;s&quot;:&quot;&quot;,&quot;search&quot;:&quot;&quot;,&quot;search_all&quot;:&quot;no&quot;,&quot;sep_month&quot;:&quot;no&quot;,&quot;show_et_ft_img&quot;:&quot;yes&quot;,&quot;show_limit&quot;:&quot;no&quot;,&quot;show_limit_ajax&quot;:&quot;no&quot;,&quot;show_limit_paged&quot;:1,&quot;show_limit_redir&quot;:&quot;&quot;,&quot;show_repeats&quot;:&quot;no&quot;,&quot;show_search&quot;:&quot;no&quot;,&quot;show_upcoming&quot;:0,&quot;show_year&quot;:&quot;no&quot;,&quot;social_share&quot;:&quot;no&quot;,&quot;sort_by&quot;:&quot;sort_date&quot;,&quot;style&quot;:&quot;&quot;,&quot;tile_bg&quot;:&quot;1&quot;,&quot;tile_bg_size&quot;:&quot;full&quot;,&quot;tile_count&quot;:&quot;2&quot;,&quot;tile_height&quot;:0,&quot;tile_style&quot;:&quot;2&quot;,&quot;tiles&quot;:&quot;no&quot;,&quot;ux_val&quot;:&quot;1&quot;,&quot;view_switcher&quot;:&quot;no&quot;,&quot;wpml_l1&quot;:&quot;&quot;,&quot;wpml_l2&quot;:&quot;&quot;,&quot;wpml_l3&quot;:&quot;&quot;,&quot;x_ids&quot;:&quot;&quot;,&quot;yl_priority&quot;:&quot;no&quot;,&quot;yl_toend&quot;:&quot;no&quot;,&quot;_cver&quot;:&quot;5.0.12&quot;}\" data-filter_data=\"{&quot;event_type&quot;:{&quot;__name&quot;:&quot;Genre&quot;,&quot;__tax&quot;:&quot;event_type&quot;,&quot;__filter_type&quot;:&quot;tax&quot;,&quot;__def_val&quot;:[11,6],&quot;__invals&quot;:[&quot;11&quot;,&quot;6&quot;],&quot;__notvals&quot;:[],&quot;__list&quot;:{&quot;all&quot;:[&quot;all&quot;,&quot;Voir tout&quot;],&quot;animation&quot;:[5,&quot;Animation&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;cafeteria&quot;:[48,&quot;Caf\\u00e9t\\u00e9ria&quot;,false,&quot;n&quot;,&quot;&quot;],&quot;caraibes&quot;:[35,&quot;Cara\\u00efbes&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;conference&quot;:[14,&quot;Conf\\u00e9rence&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;coup-de-%e2%9d%a4%ef%b8%8f&quot;:[390,&quot;Coup de \\u2764\\ufe0f&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;court-metrage&quot;:[11,&quot;Court-m\\u00e9trage&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;documentaire&quot;:[10,&quot;Documentaire&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;drame&quot;:[203,&quot;Drame&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;en-competition&quot;:[6,&quot;En comp\\u00e9tition&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;evenement&quot;:[549,&quot;Ev\\u00e8nement&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;hors-competition&quot;:[12,&quot;Hors comp\\u00e9tition&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;international&quot;:[34,&quot;International&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;jeune-public&quot;:[36,&quot;Jeune public&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;long-metrage&quot;:[8,&quot;Long m\\u00e9trage&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;madiana&quot;:[16,&quot;Madiana&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;master-class&quot;:[52,&quot;Master Class&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;musique&quot;:[153,&quot;Musique&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;rencontres&quot;:[483,&quot;Rencontres&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;salle-aime-cesaire&quot;:[18,&quot;Salle Aim\\u00e9 c\\u00e9saire&quot;,false,&quot;n&quot;,&quot;&quot;],&quot;salle-case-a-vent&quot;:[47,&quot;Salle Case \\u00e0 Vent&quot;,false,&quot;n&quot;,&quot;&quot;],&quot;salle-de-reunion&quot;:[164,&quot;Salle de r\\u00e9union&quot;,false,&quot;n&quot;,&quot;&quot;],&quot;salle-frantz-fanon&quot;:[19,&quot;Salle Frantz Fanon&quot;,false,&quot;n&quot;,&quot;&quot;],&quot;salle-la-terrasse&quot;:[384,&quot;Salle La terrasse&quot;,false,&quot;n&quot;,&quot;&quot;],&quot;samedi-21-mars&quot;:[124,&quot;Samedi 21 mars&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;scolaires&quot;:[482,&quot;Scolaires&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;vr&quot;:[13,&quot;VR&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;selection-environnement&quot;:[219,&quot;S\\u00e9lection Environnement&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;special&quot;:[524,&quot;Sp\\u00e9cial&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;tec&quot;:[15,&quot;TEC&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;toiles-du-sud&quot;:[552,&quot;Toiles Du Sud,&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;tropiques-atrium&quot;:[17,&quot;Tropiques Atrium&quot;,false,&quot;y&quot;,&quot;&quot;]},&quot;nterms&quot;:[11,6],&quot;tterms&quot;:[11,6],&quot;terms&quot;:[11,6]},&quot;event_type_2&quot;:{&quot;__name&quot;:&quot;Event Type 2&quot;,&quot;__tax&quot;:&quot;event_type_2&quot;,&quot;__filter_type&quot;:&quot;tax&quot;,&quot;__def_val&quot;:[&quot;all&quot;],&quot;__invals&quot;:[&quot;all&quot;],&quot;__notvals&quot;:[],&quot;__list&quot;:{&quot;all&quot;:[&quot;all&quot;,&quot;Voir tout&quot;],&quot;avant-premiere&quot;:[417,&quot;Avant-premi\\u00e8re&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;biopic&quot;:[200,&quot;Biopic&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;cinema-afro-americain&quot;:[498,&quot;Cin\\u00e9ma Afro-am\\u00e9ricain&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;cinema-caraibes-amerique-du-sud&quot;:[500,&quot;Cin\\u00e9ma Cara\\u00efbes Am\\u00e9rique du sud&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;cinema-dafrique&quot;:[499,&quot;Cin\\u00e9ma d&#039;Afrique&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;courts-metrage&quot;:[56,&quot;Courts-m\\u00e9trage&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;documentaire&quot;:[55,&quot;Documentaire&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;en-competition-2023&quot;:[389,&quot;En comp\\u00e9tition 2023&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;semaine-de-la-critique&quot;:[199,&quot;Semaine de la critique&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;vendredi-22-mars&quot;:[67,&quot;Vendredi 22 mars&quot;,false,&quot;y&quot;,&quot;&quot;],&quot;vendredi-29-mars&quot;:[72,&quot;Vendredi 29 mars&quot;,false,&quot;y&quot;,&quot;&quot;]},&quot;nterms&quot;:[&quot;all&quot;],&quot;tterms&quot;:[&quot;all&quot;],&quot;terms&quot;:[&quot;all&quot;]}}\" data-nav_data=\"{&quot;month_title&quot;:&quot;&lt;p id=&#039;evcal_cur&#039; class=&#039;evo_month_title padr10&#039;&gt; septembre, 2026&lt;\\\/p&gt;&quot;}\" data-od=\"{&quot;lang_no_events&quot;:&quot;No Events&quot;,&quot;cal_tz_offset&quot;:-240,&quot;cal_tz&quot;:&quot;America\\\/New_York&quot;}\" ><\/div>\r\n\t\t \t\t<div class='evo_cal_events' data-events=\"\"><\/div>\r\n\t\t \t<\/div>\r\n\t\t\t\t\r\n\t\t\t\r\n\t\t\t\t\t\t<\/div><!-- EventON End -->\r\n\t\t\t<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Prix du jury Court-m\u00e9trage.LES COURT-METRAGES EN COMP\u00c9TITION Le jury [A venir] Le jury sera d\u00e9voil\u00e9 bient\u00f4t ! [A venir] Le jury sera d\u00e9voil\u00e9 bient\u00f4t ! [A venir] Le jury sera d\u00e9voil\u00e9 bient\u00f4t !<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":12095,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-12051","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prix du jury Court-m\u00e9trage - Cin\u00e9Martinique Festival<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tropiques-atrium.fr\/cinemartinique\/les-films-en-competition\/prix-du-jury-court-metrage\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prix du jury Court-m\u00e9trage - Cin\u00e9Martinique Festival\" \/>\n<meta property=\"og:description\" content=\"Prix du jury Court-m\u00e9trage.LES COURT-METRAGES EN COMP\u00c9TITION Le jury [A venir] Le jury sera d\u00e9voil\u00e9 bient\u00f4t ! [A venir] Le jury sera d\u00e9voil\u00e9 bient\u00f4t ! [A venir] Le jury sera d\u00e9voil\u00e9 bient\u00f4t !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tropiques-atrium.fr\/cinemartinique\/les-films-en-competition\/prix-du-jury-court-metrage\/\" \/>\n<meta property=\"og:site_name\" content=\"Cin\u00e9Martinique Festival\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-04T21:14:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prix du jury Court-m\u00e9trage - Cin\u00e9Martinique Festival","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tropiques-atrium.fr\/cinemartinique\/les-films-en-competition\/prix-du-jury-court-metrage\/","og_locale":"fr_FR","og_type":"article","og_title":"Prix du jury Court-m\u00e9trage - Cin\u00e9Martinique Festival","og_description":"Prix du jury Court-m\u00e9trage.LES COURT-METRAGES EN COMP\u00c9TITION Le jury [A venir] Le jury sera d\u00e9voil\u00e9 bient\u00f4t ! [A venir] Le jury sera d\u00e9voil\u00e9 bient\u00f4t ! [A venir] Le jury sera d\u00e9voil\u00e9 bient\u00f4t !","og_url":"https:\/\/tropiques-atrium.fr\/cinemartinique\/les-films-en-competition\/prix-du-jury-court-metrage\/","og_site_name":"Cin\u00e9Martinique Festival","article_modified_time":"2024-10-04T21:14:21+00:00","og_image":[{"url":"https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tropiques-atrium.fr\/cinemartinique\/les-films-en-competition\/prix-du-jury-court-metrage\/","url":"https:\/\/tropiques-atrium.fr\/cinemartinique\/les-films-en-competition\/prix-du-jury-court-metrage\/","name":"Prix du jury Court-m\u00e9trage - Cin\u00e9Martinique Festival","isPartOf":{"@id":"https:\/\/tropiques-atrium.fr\/cinemartinique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tropiques-atrium.fr\/cinemartinique\/les-films-en-competition\/prix-du-jury-court-metrage\/#primaryimage"},"image":{"@id":"https:\/\/tropiques-atrium.fr\/cinemartinique\/les-films-en-competition\/prix-du-jury-court-metrage\/#primaryimage"},"thumbnailUrl":"https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet.jpg","datePublished":"2022-10-12T01:12:09+00:00","dateModified":"2024-10-04T21:14:21+00:00","breadcrumb":{"@id":"https:\/\/tropiques-atrium.fr\/cinemartinique\/les-films-en-competition\/prix-du-jury-court-metrage\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tropiques-atrium.fr\/cinemartinique\/les-films-en-competition\/prix-du-jury-court-metrage\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/tropiques-atrium.fr\/cinemartinique\/les-films-en-competition\/prix-du-jury-court-metrage\/#primaryimage","url":"https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet.jpg","contentUrl":"https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2019\/03\/lespri-sinema-complet.jpg","width":1600,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/tropiques-atrium.fr\/cinemartinique\/les-films-en-competition\/prix-du-jury-court-metrage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/tropiques-atrium.fr\/cinemartinique\/"},{"@type":"ListItem","position":2,"name":"Les films en comp\u00e9tition","item":"https:\/\/tropiques-atrium.fr\/cinemartinique\/les-films-en-competition\/"},{"@type":"ListItem","position":3,"name":"Prix du jury Court-m\u00e9trage"}]},{"@type":"WebSite","@id":"https:\/\/tropiques-atrium.fr\/cinemartinique\/#website","url":"https:\/\/tropiques-atrium.fr\/cinemartinique\/","name":"Cin\u00e9Martinique Festival","description":"","publisher":{"@id":"https:\/\/tropiques-atrium.fr\/cinemartinique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tropiques-atrium.fr\/cinemartinique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/tropiques-atrium.fr\/cinemartinique\/#organization","name":"Cin\u00e9Martinique Festival","url":"https:\/\/tropiques-atrium.fr\/cinemartinique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/tropiques-atrium.fr\/cinemartinique\/#\/schema\/logo\/image\/","url":"https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2022\/01\/CineMartinique-logo-1.png","contentUrl":"https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-content\/uploads\/sites\/3\/2022\/01\/CineMartinique-logo-1.png","width":1205,"height":362,"caption":"Cin\u00e9Martinique Festival"},"image":{"@id":"https:\/\/tropiques-atrium.fr\/cinemartinique\/#\/schema\/logo\/image\/"}}]}},"amp_enabled":false,"_links":{"self":[{"href":"https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-json\/wp\/v2\/pages\/12051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-json\/wp\/v2\/comments?post=12051"}],"version-history":[{"count":38,"href":"https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-json\/wp\/v2\/pages\/12051\/revisions"}],"predecessor-version":[{"id":15137,"href":"https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-json\/wp\/v2\/pages\/12051\/revisions\/15137"}],"up":[{"embeddable":true,"href":"https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-json\/wp\/v2\/pages\/12095"}],"wp:attachment":[{"href":"https:\/\/tropiques-atrium.fr\/cinemartinique\/wp-json\/wp\/v2\/media?parent=12051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}